{"id":20414,"date":"2025-06-02T12:06:14","date_gmt":"2025-06-02T16:06:14","guid":{"rendered":"https:\/\/web.uri.edu\/cels\/?page_id=20414"},"modified":"2026-04-24T09:16:47","modified_gmt":"2026-04-24T13:16:47","slug":"room-reservation","status":"publish","type":"page","link":"https:\/\/web.uri.edu\/cels\/room-reservation\/","title":{"rendered":"Van and Room Reservation"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScmFAeqkJV6wixtQA1-gvPj3XHa7OazPMLNnTs1dITFFuV3aQ\/viewform\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/bus.jpg\" srcset=\"\" alt=\"picture of a bus\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>Van Reservation<\/h2><p><strong>Vans Available<\/strong><br><strong><em>27 Passenger Minibus<br>14 Passenger Van (Driver MUST be at least 25yrs old)<br>12 Passenger Van<br>11 Passenger Van x 4<br>2 Passenger Truck<\/em><\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Van<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?src=c_d1ad92ee0921a96b1d480371dfef62d3ff195ca5a0aa60313dc06757f72b822a%40group.calendar.google.com&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV9sZHM1bWNidTg3amhiMXNkNXJvZ2szNzhrY0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23b39ddb\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">CBLS Building<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/forms.gle\/QJrND52XWNnWZcxr5\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/cbls-436-e1748632097361.jpg\" srcset=\"\" alt=\"conference room cels 436\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>CBLS \u2013 Room 435<\/h2><p><strong>20 seat capacity<br>Wi-Fi<br>Projector<br>Computer<br>Laptop hook-up ready<br>Surround sound<\/strong><br><em>Restrictions to scheduling: Only meetings and thesis defenses; not available for classroom use.<\/em><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV9sZHM1bWNidTg3amhiMXNkNXJvZ2szNzhrY0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23b39ddb\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfh3rV-4xj1L9viVYMQ3gtxA8IMT9V-N_7ONzaFrs5IlHb4TQ\/viewform?usp=sharing&amp;ouid=118064843789373357214\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/Atrium-e1777036599972.jpg\" srcset=\"\" alt=\"Picture of the open space in CBLS ground floor which is the Atrium\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>CBLS \u2013 Atrium<\/h2><p><strong>Wi-Fi<br>Projector<br>Computer<br>Laptop hook-up ready<br>Surround sound<\/strong><br><strong>Assorted other seating<br>Indoor\/Outdoor capacity<\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV90amdkbDdob3NpaWZwaHVmMjc5OG1qMTRzZ0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23f09300\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<h2 class=\"wp-block-heading\">Woodward Building<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/forms.gle\/4mnM8axEv1pnKqyRA\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/WW-06.jpg\" srcset=\"\" alt=\"WW 06\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>WoodWard Hall \u2013 Room 006<\/h2><p><strong>21 Computers<br>Wi-Fi<br>Projector<br>Printer<\/strong><br><strong>Plotter<\/strong><br><br><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV9vZWYxbDY1ZDlub2d1ZXJpc3UxdmZyMTJqOEBncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23e4c441\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSek7wGtFKoEVUXjYJl1SuVLUhnn7eUIc0NYhG_lHj5i6k1TVg\/viewform?usp=dialog\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/WW-09.jpg\" srcset=\"\" alt=\"WW 09\n\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>WoodWard Hall \u2013 Room 009<\/h2><p><strong>20 seat capacity<br>Wi-Fi<br>Projector<br><\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV9pZDdibWIxb29rYTVjNm10cmhvMnQzMTBrZ0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%237cb342\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeCA3h84uKhtXuIH43RweTowCN9vBmSTwq7e5x-UNIiNU5kBQ\/viewform?usp=sharing&amp;ouid=118064843789373357214\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/20250530_121652-scaled-e1748631837282.jpg\" srcset=\"\" alt=\"WW 115\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>WoodWard Hall \u2013 Room 115<\/h2><p><strong>12 seat capacity<br>Wi-Fi<br>White Board<br><\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=Y19jNmNlZmZiY2EyNGExZmVjMDQzMTczNjVlOWM3MmFkYzg0MmYwYjZkYTdlNjdjNDM2YWZiMTc5N2VlMWYwZDhkQGdyb3VwLmNhbGVuZGFyLmdvb2dsZS5jb20&#038;color=%23009688\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfV2iDdZl_VW4N-cC56uDJFuj4KmuxzCNv24fQcWzLNhSrCuA\/viewform?usp=sharing&amp;ouid=118064843789373357214\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/WW312.jpg\" srcset=\"\" alt=\"WW312\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>WoodWard Hall \u2013 Room 312<\/h2><p><strong><strong>12 seat capacity<br>Wi-Fi<br>White Board<\/strong><br><\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">REserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV91ZTM3MzMzaXI4bDJkbDBna2o3bHVjajVub0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%233f51b5\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/forms.gle\/VXgpxYhbQEJBDabG8\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/WW313.jpg\" srcset=\"\" alt=\"\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>WoodWard Hall \u2013 Room 313<\/h2><p><strong><strong>7 seat capacity<br>Wi-Fi<br><\/strong><\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">REserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=Y19mZDgyNTEzMGFlYmQzZmI2MTIxZWViNDA1YjJlYWI0MzdhNDZjMGIxMWZiMTM4NzY2M2JkODg5YjNlMGEwYWU1QGdyb3VwLmNhbGVuZGFyLmdvb2dsZS5jb20&#038;color=%237cb342\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<h2 class=\"wp-block-heading\">Green House Building<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfQytmglV5aj74tnQCSy4FMZ5cxHXk2UwTxGPnQ8v5Sge5U8Q\/viewform?usp=sharing&amp;ouid=118064843789373357214\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/Green-House-123.jpg\" srcset=\"\" alt=\"Green House 123\n\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>GreenHouse \u2013 Room 123<\/h2><p><strong>20 seat capacity<br>Wi-Fi<br>Projector<\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?src=c_fd825130aebd3fb6121eeb405b2eab437a46c0b11fb1387663bd889b3e0a0ae5%40group.calendar.google.com&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV9mZjZpYXRhOWsybWlycXJobWFtcWtoZXZmb0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23e4c441\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<h2 class=\"wp-block-heading\">Coastal Building<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdBSry68S0ziXZBOhXmFcv_FIQuXPDjxphl7FyrYrRiyoGW0w\/viewform?usp=dialog\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/20250530_123721-scaled-e1748632699351.jpg\" srcset=\"\" alt=\"\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>Coastal Room 001<\/h2><p><strong>8 seat capacity<br>Wi-Fi<br>TV<\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV8yYjUzdjMyM2lubXBvNTFsYzFxZWo5NHNoMEBncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%234285f4\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScQEFtsYKBpw63EYkOx_kqT5qe7UKWmjZwMVB-d1gbzSVmHeg\/viewform?usp=dialog\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/20250530_124809.jpg\" srcset=\"\" alt=\"Coastal 026\n\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>Coastal Room 026<\/h2><p><strong>8 seat capacity<br>Wi-Fi<br>White Board<\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV8waHU2MzI5MHBwMW11MnQ1OTlxajdkbmdrMEBncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23b39ddb\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeH18IZRUgA027VTesp5aQ1cRc0hsFQQInsZoYWpeWxVRo35A\/viewform?usp=dialog\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/Coatal-115.jpg\" srcset=\"\" alt=\"Coastal 117A\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>Coastal Room 117 A<\/h2><p><strong>20 seat capacity<br>Wi-Fi<br>White board<\/strong><br><strong>TV<\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV91NHMxOHRvaWhqYTRxcjY1MXZ0cTdhbW90MEBncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%237cb342\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScBfx5tEMKj51MwVW-HxpocKBQMGwmCbnyGxUvyEM25UHhu0A\/viewform?usp=dialog\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/WW-201.jpg\" srcset=\"\" alt=\"\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>Coastal Room 200a<\/h2><p><strong>8 seat capacity<br>Wi-Fi<br>White Board<\/strong><br><strong>TV<\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV9uYW45M2dhMHBuaGk5Nm42ZmQxNDNhMXZka0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23f6bf26\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"cl-wrapper cl-card-wrapper\"><a class=\"cl-card  \" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSerlfX_uNcM-vj-SszG6U1KoU4Dajg1mur5_Hjx66EayzgldA\/viewform?usp=dialog\" title=\"\"><div class=\"cl-card-container media\"><img decoding=\"async\" src=\"https:\/\/web.uri.edu\/cels\/wp-content\/uploads\/sites\/2130\/WW200.jpg\" srcset=\"\" alt=\"\"><\/div><div class=\"cl-card-container text\"><div class=\"cl-card-text\"><h2>Coastal Room 201<\/h2><p><strong>15 seat capacity<br>Wi-Fi<\/strong><br><strong>TV<br>White Board<\/strong><\/p><\/div><\/div><div class=\"cl-card-container button\">Reserve Room<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<!-- iframe plugin v.6.0 wordpress.org\/plugins\/iframe\/ -->\n<iframe loading=\"lazy\" src=\"https:\/\/calendar.google.com\/calendar\/embed?height=600&#038;wkst=1&#038;ctz=America%2FNew_York&#038;showPrint=0&#038;mode=WEEK&#038;src=dXJpLmVkdV80dWlmcHQ5NTZtdjFwZWl1NjgzNmxvNjZqY0Bncm91cC5jYWxlbmRhci5nb29nbGUuY29t&#038;color=%23e67c73\" style=\"border:solid 1px #777\" width=\"600\" height=\"600\" frameborder=\"0\" scrolling=\"no\" class=\"iframe-class\"><\/iframe>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CBLS Building Woodward Building Green House Building Coastal Building<\/p>\n","protected":false},"author":5144,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-20414","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/pages\/20414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/users\/5144"}],"replies":[{"embeddable":true,"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/comments?post=20414"}],"version-history":[{"count":4,"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/pages\/20414\/revisions"}],"predecessor-version":[{"id":21530,"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/pages\/20414\/revisions\/21530"}],"wp:attachment":[{"href":"https:\/\/web.uri.edu\/cels\/wp-json\/wp\/v2\/media?parent=20414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}